{"id":370,"date":"2023-10-04T11:15:50","date_gmt":"2023-10-04T11:15:50","guid":{"rendered":"https:\/\/pro.edelifeclinicaltrial.com\/?page_id=370"},"modified":"2026-04-23T16:05:56","modified_gmt":"2026-04-23T16:05:56","slug":"centros-del-ensayo-clinico","status":"publish","type":"page","link":"https:\/\/pro.edelifeclinicaltrial.com\/es\/centros-del-ensayo-clinico\/","title":{"rendered":"Centros del ensayo cl\u00ednico"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-370","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centros del ensayo cl\u00ednico | Pro Edelifclinicaltrial<\/title>\n<meta name=\"description\" content=\"Incluir un paciente al estudio Edelife \u00bfTiene alguna pregunta? P\u00f3ngase en contacto con un m\u00e9dico del estudio en uno de los centros del estudio de todo el mundo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pro.edelifeclinicaltrial.com\/es\/centros-del-ensayo-clinico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centros del ensayo cl\u00ednico | Pro Edelifclinicaltrial\" \/>\n<meta property=\"og:description\" content=\"Incluir un paciente al estudio Edelife \u00bfTiene alguna pregunta? P\u00f3ngase en contacto con un m\u00e9dico del estudio en uno de los centros del estudio de todo el mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pro.edelifeclinicaltrial.com\/es\/centros-del-ensayo-clinico\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Edelifclinicaltrial\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T16:05:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/centros-del-ensayo-clinico\\\/\",\"url\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/centros-del-ensayo-clinico\\\/\",\"name\":\"Centros del ensayo cl\u00ednico | Pro Edelifclinicaltrial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/#website\"},\"datePublished\":\"2023-10-04T11:15:50+00:00\",\"dateModified\":\"2026-04-23T16:05:56+00:00\",\"description\":\"Incluir un paciente al estudio Edelife \u00bfTiene alguna pregunta? P\u00f3ngase en contacto con un m\u00e9dico del estudio en uno de los centros del estudio de todo el mundo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/centros-del-ensayo-clinico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/centros-del-ensayo-clinico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/centros-del-ensayo-clinico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centros del ensayo cl\u00ednico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/\",\"name\":\"Edelife HCP\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/#organization\",\"name\":\"Edelife HCP\",\"url\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo-edelife-trsp.png\",\"contentUrl\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo-edelife-trsp.png\",\"width\":733,\"height\":485,\"caption\":\"Edelife HCP\"},\"image\":{\"@id\":\"https:\\\/\\\/pro.edelifeclinicaltrial.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centros del ensayo cl\u00ednico | Pro Edelifclinicaltrial","description":"Incluir un paciente al estudio Edelife \u00bfTiene alguna pregunta? P\u00f3ngase en contacto con un m\u00e9dico del estudio en uno de los centros del estudio de todo el mundo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pro.edelifeclinicaltrial.com\/es\/centros-del-ensayo-clinico\/","og_locale":"es_ES","og_type":"article","og_title":"Centros del ensayo cl\u00ednico | Pro Edelifclinicaltrial","og_description":"Incluir un paciente al estudio Edelife \u00bfTiene alguna pregunta? P\u00f3ngase en contacto con un m\u00e9dico del estudio en uno de los centros del estudio de todo el mundo.","og_url":"https:\/\/pro.edelifeclinicaltrial.com\/es\/centros-del-ensayo-clinico\/","og_site_name":"Pro Edelifclinicaltrial","article_modified_time":"2026-04-23T16:05:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pro.edelifeclinicaltrial.com\/es\/centros-del-ensayo-clinico\/","url":"https:\/\/pro.edelifeclinicaltrial.com\/es\/centros-del-ensayo-clinico\/","name":"Centros del ensayo cl\u00ednico | Pro Edelifclinicaltrial","isPartOf":{"@id":"https:\/\/pro.edelifeclinicaltrial.com\/es\/#website"},"datePublished":"2023-10-04T11:15:50+00:00","dateModified":"2026-04-23T16:05:56+00:00","description":"Incluir un paciente al estudio Edelife \u00bfTiene alguna pregunta? P\u00f3ngase en contacto con un m\u00e9dico del estudio en uno de los centros del estudio de todo el mundo.","breadcrumb":{"@id":"https:\/\/pro.edelifeclinicaltrial.com\/es\/centros-del-ensayo-clinico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pro.edelifeclinicaltrial.com\/es\/centros-del-ensayo-clinico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pro.edelifeclinicaltrial.com\/es\/centros-del-ensayo-clinico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pro.edelifeclinicaltrial.com\/es\/"},{"@type":"ListItem","position":2,"name":"Centros del ensayo cl\u00ednico"}]},{"@type":"WebSite","@id":"https:\/\/pro.edelifeclinicaltrial.com\/es\/#website","url":"https:\/\/pro.edelifeclinicaltrial.com\/es\/","name":"Edelife HCP","description":"","publisher":{"@id":"https:\/\/pro.edelifeclinicaltrial.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pro.edelifeclinicaltrial.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pro.edelifeclinicaltrial.com\/es\/#organization","name":"Edelife HCP","url":"https:\/\/pro.edelifeclinicaltrial.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pro.edelifeclinicaltrial.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/pro.edelifeclinicaltrial.com\/wp-content\/uploads\/2023\/10\/logo-edelife-trsp.png","contentUrl":"https:\/\/pro.edelifeclinicaltrial.com\/wp-content\/uploads\/2023\/10\/logo-edelife-trsp.png","width":733,"height":485,"caption":"Edelife HCP"},"image":{"@id":"https:\/\/pro.edelifeclinicaltrial.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/pro.edelifeclinicaltrial.com\/es\/wp-json\/wp\/v2\/pages\/370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pro.edelifeclinicaltrial.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pro.edelifeclinicaltrial.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pro.edelifeclinicaltrial.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pro.edelifeclinicaltrial.com\/es\/wp-json\/wp\/v2\/comments?post=370"}],"version-history":[{"count":2,"href":"https:\/\/pro.edelifeclinicaltrial.com\/es\/wp-json\/wp\/v2\/pages\/370\/revisions"}],"predecessor-version":[{"id":566,"href":"https:\/\/pro.edelifeclinicaltrial.com\/es\/wp-json\/wp\/v2\/pages\/370\/revisions\/566"}],"wp:attachment":[{"href":"https:\/\/pro.edelifeclinicaltrial.com\/es\/wp-json\/wp\/v2\/media?parent=370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}